{"id":7719,"date":"2022-04-12T18:39:02","date_gmt":"2022-04-12T16:39:02","guid":{"rendered":"https:\/\/aedcoro.com\/?p=7719"},"modified":"2022-04-12T18:39:02","modified_gmt":"2022-04-12T16:39:02","slug":"jornada-de-direccion-coral","status":"publish","type":"post","link":"https:\/\/aedcoro.dev-r.xiro.es\/en\/jornada-de-direccion-coral\/","title":{"rendered":"Jornada de Direcci\u00f3n Coral"},"content":{"rendered":"<div dir=\"auto\">\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"f4hce-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"f4hce-0-0\"><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-7588 alignleft\" src=\"\/wp-content\/uploads\/Jornada-Coral-Barakaldo.jpg\" alt=\"\" width=\"400\" height=\"400\" \/>JORNADA DE DIRECCI\u00d3N CORAL<\/strong><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"2ctj6-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"2ctj6-0-0\"><span data-offset-key=\"2ctj6-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"6lu4n-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"6lu4n-0-0\"><span data-offset-key=\"6lu4n-0-0\">Os invitamos a la pr\u00f3xima Jornada de Direcci\u00f3n Coral que se celebrar\u00e1 el pr\u00f3ximo <b>30 de abril (s\u00e1bado) en en Barakaldo (Bizkaia)<\/b>.<\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"c9n1v-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"c9n1v-0-0\"><span data-offset-key=\"c9n1v-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"e2927-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"e2927-0-0\"><span data-offset-key=\"e2927-0-0\">Entre otras actividades, disfrutaremos de una Masterclass con Erik Nielsen (USA) y tendremos un encuentro con los compositores premiados en el Gran Premio BBK.\n<\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"2181b-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"2181b-0-0\"><span data-offset-key=\"2181b-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"3ka9s\" data-offset-key=\"8n5q8-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"8n5q8-0-0\"><span data-offset-key=\"8n5q8-0-0\">La jornada se podr\u00e1 seguir tanto de manera presencial como online. <\/span><\/div>\n<p>Os dejamos aqu\u00ed el enlace al <a href=\"\/wp-content\/uploads\/Programa-Jornada-Barakaldo-2022.pdf\" target=\"_blank\" rel=\"noopener\">programa de la jornada<\/a>.<\/p>\n<p><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdJNYR3qlCQvqdeXSFkT3furEUCcopmO4S7bY7Q7ytjBlbisA\/viewform\" target=\"_blank\" rel=\"noopener\"><b>INSCRIPCIONES A LA JORNADA<\/b><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>JORNADA DE DIRECCI\u00d3N CORAL \u00a0 Os invitamos a la pr\u00f3xima Jornada de Direcci\u00f3n Coral que se celebrar\u00e1 el pr\u00f3ximo 30 de abril (s\u00e1bado) en en Barakaldo (Bizkaia). \u00a0 Entre otras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7719","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornada de Direcci\u00f3n Coral - AEDCORO<\/title>\n<meta name=\"description\" content=\"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada de Direcci\u00f3n Coral - AEDCORO\" \/>\n<meta property=\"og:description\" content=\"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aedcoro.dev-r.xiro.es\/en\/jornada-de-direccion-coral\/\" \/>\n<meta property=\"og:site_name\" content=\"AEDCORO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aedcoro\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-12T16:39:02+00:00\" \/>\n<meta name=\"author\" content=\"ORIX ORIX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aedcoro\" \/>\n<meta name=\"twitter:site\" content=\"@aedcoro\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ORIX ORIX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/\"},\"author\":{\"name\":\"ORIX ORIX\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#\\\/schema\\\/person\\\/50e12e11b68c62ca3a5aef43b1dfcb1d\"},\"headline\":\"Jornada de Direcci\u00f3n Coral\",\"datePublished\":\"2022-04-12T16:39:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/\"},\"wordCount\":84,\"publisher\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/\",\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/\",\"name\":\"Jornada de Direcci\u00f3n Coral - AEDCORO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#website\"},\"datePublished\":\"2022-04-12T16:39:02+00:00\",\"description\":\"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/jornada-de-direccion-coral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornada de Direcci\u00f3n Coral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#website\",\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/\",\"name\":\"AEDCORO\",\"description\":\"Asociaci\u00f3n Espa\u00f1ola de Directores de Coro\",\"publisher\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#organization\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola de Directores de Coro\",\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/wp-content\\\/uploads\\\/AEDCoro_logo.webp\",\"contentUrl\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/wp-content\\\/uploads\\\/AEDCoro_logo.webp\",\"width\":500,\"height\":395,\"caption\":\"Asociaci\u00f3n Espa\u00f1ola de Directores de Coro\"},\"image\":{\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aedcoro\\\/\",\"https:\\\/\\\/x.com\\\/aedcoro\",\"https:\\\/\\\/www.instagram.com\\\/aedcoro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCx3RJQ3BMA4KmkstsrIZk-w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/#\\\/schema\\\/person\\\/50e12e11b68c62ca3a5aef43b1dfcb1d\",\"name\":\"ORIX ORIX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/wp-content\\\/litespeed\\\/avatar\\\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297\",\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/wp-content\\\/litespeed\\\/avatar\\\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297\",\"contentUrl\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/wp-content\\\/litespeed\\\/avatar\\\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297\",\"caption\":\"ORIX ORIX\"},\"description\":\"BLABLABLABLABALBALBA\",\"sameAs\":[\"https:\\\/\\\/aedcoro.dev-r.xiro.es\"],\"url\":\"https:\\\/\\\/aedcoro.dev-r.xiro.es\\\/en\\\/author\\\/orixwp\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada de Direcci\u00f3n Coral - AEDCORO","description":"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Jornada de Direcci\u00f3n Coral - AEDCORO","og_description":"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?","og_url":"https:\/\/aedcoro.dev-r.xiro.es\/en\/jornada-de-direccion-coral\/","og_site_name":"AEDCORO","article_publisher":"https:\/\/www.facebook.com\/aedcoro\/","article_published_time":"2022-04-12T16:39:02+00:00","author":"ORIX ORIX","twitter_card":"summary_large_image","twitter_creator":"@aedcoro","twitter_site":"@aedcoro","twitter_misc":{"Written by":"ORIX ORIX","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/#article","isPartOf":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/"},"author":{"name":"ORIX ORIX","@id":"https:\/\/aedcoro.dev-r.xiro.es\/#\/schema\/person\/50e12e11b68c62ca3a5aef43b1dfcb1d"},"headline":"Jornada de Direcci\u00f3n Coral","datePublished":"2022-04-12T16:39:02+00:00","mainEntityOfPage":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/"},"wordCount":84,"publisher":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/#organization"},"articleSection":["Noticias"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/","url":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/","name":"Jornada de Direcci\u00f3n Coral - AEDCORO","isPartOf":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/#website"},"datePublished":"2022-04-12T16:39:02+00:00","description":"Este fin de semana se celebra en la localidad alicantina de Concentaina la edici\u00f3n n\u00ba 41 del Certamen Coral Fira de Tots Sants ?","breadcrumb":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aedcoro.dev-r.xiro.es\/jornada-de-direccion-coral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aedcoro.dev-r.xiro.es\/"},{"@type":"ListItem","position":2,"name":"Jornada de Direcci\u00f3n Coral"}]},{"@type":"WebSite","@id":"https:\/\/aedcoro.dev-r.xiro.es\/#website","url":"https:\/\/aedcoro.dev-r.xiro.es\/","name":"AEDCORO","description":"Spanish Association of Choir Directors","publisher":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aedcoro.dev-r.xiro.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/aedcoro.dev-r.xiro.es\/#organization","name":"Spanish Association of Choir Directors","url":"https:\/\/aedcoro.dev-r.xiro.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aedcoro.dev-r.xiro.es\/#\/schema\/logo\/image\/","url":"https:\/\/aedcoro.dev-r.xiro.es\/wp-content\/uploads\/AEDCoro_logo.webp","contentUrl":"https:\/\/aedcoro.dev-r.xiro.es\/wp-content\/uploads\/AEDCoro_logo.webp","width":500,"height":395,"caption":"Asociaci\u00f3n Espa\u00f1ola de Directores de Coro"},"image":{"@id":"https:\/\/aedcoro.dev-r.xiro.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aedcoro\/","https:\/\/x.com\/aedcoro","https:\/\/www.instagram.com\/aedcoro\/","https:\/\/www.youtube.com\/channel\/UCx3RJQ3BMA4KmkstsrIZk-w"]},{"@type":"Person","@id":"https:\/\/aedcoro.dev-r.xiro.es\/#\/schema\/person\/50e12e11b68c62ca3a5aef43b1dfcb1d","name":"ORIX ORIX","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aedcoro.dev-r.xiro.es\/wp-content\/litespeed\/avatar\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297","url":"https:\/\/aedcoro.dev-r.xiro.es\/wp-content\/litespeed\/avatar\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297","contentUrl":"https:\/\/aedcoro.dev-r.xiro.es\/wp-content\/litespeed\/avatar\/3b039e439a2fe26c16daa4cc76b48827.jpg?ver=1788269297","caption":"ORIX ORIX"},"description":"BLABLABLABLABALBALBA","sameAs":["https:\/\/aedcoro.dev-r.xiro.es"],"url":"https:\/\/aedcoro.dev-r.xiro.es\/en\/author\/orixwp\/"}]}},"_links":{"self":[{"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/posts\/7719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/comments?post=7719"}],"version-history":[{"count":0,"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/posts\/7719\/revisions"}],"wp:attachment":[{"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/media?parent=7719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/categories?post=7719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aedcoro.dev-r.xiro.es\/en\/wp-json\/wp\/v2\/tags?post=7719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}